{"id":261,"date":"2021-03-29T12:25:38","date_gmt":"2021-03-29T12:25:38","guid":{"rendered":"https:\/\/biopsafe.com\/?page_id=261"},"modified":"2023-10-30T19:41:31","modified_gmt":"2023-10-30T19:41:31","slug":"biopsafe","status":"publish","type":"page","link":"https:\/\/biopsafe.com\/it\/","title":{"rendered":"BiopSafe"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=&#8221;.vc_custom_1697125624710{background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/Axlab-22-06-234490_biopsafe.jpg?id=956) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;hdr-video&#8221;][vc_column][vc_raw_html]JTNDdmlkZW8lMjBwbGF5c2lubGluZSUzRCUyMnBsYXlzaW5saW5lJTIyJTIwYXV0b3BsYXklM0QlMjJhdXRvcGxheSUyMiUyMG11dGVkJTNEJTIybXV0ZWQlMjIlMjBsb29wJTNEJTIybG9vcCUyMiUzRSUwQSUzQ3NvdXJjZSUyMHNyYyUzRCUyMmh0dHBzJTNBJTJGJTJGYmlvcHNhZmUuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIzJTJGMTAlMkZBeGxhYi1CaW9wU2FmZS1yZXZpZXctdjAxLTEubXA0JTIyJTNFJTBBJTNDJTJGdmlkZW8lM0U=[\/vc_raw_html][vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;Sicuro Facile Veloce&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;intro&#8221;][vc_column][vc_row_inner el_class=&#8221;wrapper&#8221;][vc_column_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<ul>\n<li>Formalina incapsulata nel tappo<\/li>\n<li>Facile da utilizzare con una semplice pressione del dito<\/li>\n<li>Personale non esposto<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1697126671337{margin-bottom: 5px !important;background-color: #447184 !important;}&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column_inner el_class=&#8221;box-wrap white&#8221; width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;box&#8221;]\n<h2>Risoluzione di un problema per gli staff medici di tutto il mondo<\/h2>\n<p>Negli ospedali e nelle cliniche vengono effettuate ogni giorno milioni di biopsie. Tale procedura comporta generalmente l&#8217;utilizzo di formalina la quale costituisce un grave rischio per la salute.<\/p>\n<p>BiopSafe offre una soluzione efficace a questo problema. Si tratta di un nuovissimo metodo rivoluzionario per la gestione delle biopsie che aiuta a proteggere il personale medico di tutto il mondo. Il contenitore BiopSafe offre una gestione sicura della formalina con una semplice pressione del dito. [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1697126001881{background-color: #447184 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_raw_html]JTNDZGl2JTIwc3R5bGUlM0QlMjJ0ZXh0LWFsaWduJTNBY2VudGVyJTNCJTIyJTNFJTBBJTNDdmlkZW8lMjBzdHlsZSUzRCUyMm9iamVjdC1maXQlM0ElMjBjb3ZlciUzQiUyMG1heC1oZWlnaHQlM0E0MjBweCUzQiUyMG1heC13aWR0aCUzQTEwMCUyNSUzQiUyMiUyMGNvbnRyb2xzJTIwcG9zdGVyJTNEJTIyaHR0cHMlM0ElMkYlMkZiaW9wc2FmZS5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjMlMkYwNiUyRmJyYW5kLmpwZyUyMiUzRSUwQSUyMCUyMCUzQ3NvdXJjZSUyMHNyYyUzRCUyMmh0dHBzJTNBJTJGJTJGYWRyZXN1bHQuZGslMkZsJTJGYmlvcHNhZmUlMkZicmFuZC0yLm1wNCUyMiUyMHR5cGUlM0QlMjJ2aWRlbyUyRm1wNCUyMiUzRSUwQSUzQyUyRnZpZGVvJTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1697126675129{margin-bottom: 5px !important;background-color: #447184 !important;}&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1697126725730{background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/Axlab-22-06-234490_biopsafe.jpg?id=956) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_empty_space height=&#8221;400px&#8221;][\/vc_column_inner][vc_column_inner el_class=&#8221;box-wrap white&#8221; width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;box&#8221;]\n<h2>La soluzione \u00e8 semplice ed efficace<\/h2>\n<p>La grande sfida degli ospedali e delle cliniche di tutto il mondo riguarda la fissazione in formalina senza fuoriuscite o vapori.<\/p>\n<p>Grazie a BiopSafe abbiamo la soluzione a questo problema &#8211; un piccolo contenitore con formalina incapsulata nel tappo. Una leggera pressione del dito \u00e8 sufficiente affinch\u00e9 la formalina venga rilasciata in un sistema chiuso coprendo la biopsia e, allo stesso modo, facendo s\u00ec che il personale non venga esposto al contenuto, sia esso in forma liquida o di vapore.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1697126680037{margin-bottom: 5px !important;background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/bi-3-1v2.jpg?id=964) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;sizes&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; gap=&#8221;30&#8243; el_class=&#8221;wrapper&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInLeft&#8221;]\n<h3>Facile e veloce<\/h3>\n<p>Il metodo, oltre ad essere sicuro, \u00e8 anche rapido. BiopSafe \u00e8 sempre a portata di mano e bastano pochi secondi per immettere la biopsia nel contenitore e aggiungere la formalina. La sua semplicit\u00e0 di utilizzo consente di risparmiare tempo, permettendo a medici e infermieri di concentrarsi su altri aspetti importanti del loro mestiere. Allo stesso tempo garantisce un trasporto facile e sicuro presso il laboratorio.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;550px&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInRight&#8221;]\n<h3>2 volumi<\/h3>\n<p>I nostri contenitori sono disponibili in 2 volumi: 20 ml e 60 ml. Ci\u00f2 semplifica la gestione di pi\u00f9 biopsie contemporaneamente. Prima dell&#8217;avvitamento del coperchio e del rilascio della formalina, ogni biopsia pu\u00f2 essere collocata all&#8217;interno di cassette per contenitori sovrapponibili.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_section content_placement=&#8221;middle&#8221; el_class=&#8221;steps&#8221; css=&#8221;.vc_custom_1697126684193{margin-bottom: 5px !important;background-color: #447184 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;wrapper&#8221;][vc_column][vc_row_inner content_placement=&#8221;middle&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInLeft&#8221;]\n<h3>Gestione sicura della<br \/>\nbiopsia in 6 passi<\/h3>\n<p>Bastano pochi secondi affinch\u00e9 la biopsia risulti correttamente coperta dalla formalina e pronta per essere trasportata. Il tutto viene trattato all\u2019interno di un sistema chiuso ermeticamente senza perdite o fuoriuscite di vapore dal contenitore.<br \/>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_raw_html]JTNDZGl2JTIwc3R5bGUlM0QlMjJ0ZXh0LWFsaWduJTNBY2VudGVyJTNCJTIyJTNFJTBBJTNDdmlkZW8lMjBzdHlsZSUzRCUyMm9iamVjdC1maXQlM0ElMjBjb3ZlciUzQiUyMG1heC1oZWlnaHQlM0E0MjBweCUzQiUyMG1heC13aWR0aCUzQTEwMCUyNSUzQiUyMiUyMGNvbnRyb2xzJTIwcG9zdGVyJTNEJTIyaHR0cHMlM0ElMkYlMkZiaW9wc2FmZS5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjMlMkYwNiUyRmhvdzIuanBnJTIyJTNFJTBBJTIwJTIwJTNDc291cmNlJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZhZHJlc3VsdC5kayUyRmwlMkZiaW9wc2FmZSUyRmhvdy0yLm1wNCUyMiUyMHR5cGUlM0QlMjJ2aWRlbyUyRm1wNCUyMiUzRSUwQSUzQyUyRnZpZGVvJTNFJTBBJTNDJTJGZGl2JTNF[\/vc_raw_html][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#8221;protection&#8221; css=&#8221;.vc_custom_1697126688803{margin-bottom: 5px !important;background-color: #447184 !important;}&#8221;][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column width=&#8221;2\/5&#8243; css=&#8221;.vc_custom_1697126714913{background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/Axlab-22-06-234433-1.jpg?id=971) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_single_image image=&#8221;93&#8243; img_size=&#8221;&#8221; alignment=&#8221;right&#8221;][\/vc_column][vc_column width=&#8221;3\/5&#8243; el_class=&#8221;protection-text white&#8221;][vc_row_inner][vc_column_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<h2>BiopSafe &#8211; La tua protezione quotidiana<\/h2>\n<p>La formaldeide \u00e8 cancerogena per l&#8217;essere umano e in grado di influire negativamente sulla salute in vari modi, sia attraverso l&#8217;esposizione diretta che mediante l\u2019inalazione. \u00c8 stato ampiamente dimostrato come l&#8217;esposizione a lungo termine alla formaldeide sia in grado di aumentare il rischio di cancro del naso, del rinofaringe e del polmone.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1617010347851{margin-bottom: 0px !important;border-bottom-width: 0px !important;}&#8221;][vc_column_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<h5 style=\"text-align: center;\">Anche un&#8217;esposizione a breve termine pu\u00f2 provocare seri rischi per la salute:<\/h5>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner gap=&#8221;20&#8243;][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"text-align: center;\"><strong>Inalazione:<\/strong><br \/>\nUna maggiore esposizione alla formaldeide pu\u00f2 causare gravi reazioni polmonari alle vie respiratorie superiori<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"text-align: center;\"><strong>Occhi:<\/strong><br \/>\nIrritazione con conseguente arrossamento, prurito, bruciore e lacrimazione.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<p style=\"text-align: center;\"><strong>Pelle:<\/strong><br \/>\nReazioni allergiche e dermatiti, come sperimentato da molti di coloro che lavorano con la formaldeide.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1617010347851{margin-bottom: 0px !important;border-bottom-width: 0px !important;}&#8221;][vc_column_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\u00c8 quindi fondamentale maneggiare la formalina con cura e attenzione, al fine di garantire un ambiente di lavoro sicuro. [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][\/vc_section][vc_row css=&#8221;.vc_custom_1697126694095{margin-bottom: 5px !important;background-color: #f4f4f4 !important;}&#8221; el_id=&#8221;about&#8221; el_class=&#8221;about&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column_inner el_class=&#8221;about-text&#8221; width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInLeft&#8221; el_class=&#8221;box&#8221;]\n<h2>Chi siamo<\/h2>\n<p><span style=\"font-weight: 400;\">Siamo fortemente impegnati a garantire un ambiente di lavoro sicuro per il personale medico coinvolto nelle procedure bioptiche e a diffondere una maggiore consapevolezza dei numerosi rischi per la salute associati all&#8217;esposizione alla formalina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Per questo motivo, nel 2014 abbiamo sviluppato BiopSafe, una soluzione innovativa che non solo elimina qualsiasi esposizione alla formalina durante la procedura, ma \u00e8 anche rapida e facile da utilizzare. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">BiopSafe fa parte del Axlab, specializzato nell\u2019offrire soluzioni in ambito patologico. Oggi BiopSafe \u00e8 utilizzato da migliaia di operatori sanitari di tutto il mondo ed \u00e8 distribuito a livello globale attraverso una rete di partner dedicati.<\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1697126705120{background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/Axlab-22-06-234399_biopsafe.jpg?id=938) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_empty_space height=&#8221;400px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row css=&#8221;.vc_custom_1697125624710{background-image: url(https:\/\/biopsafe.com\/wp-content\/uploads\/2023\/10\/Axlab-22-06-234490_biopsafe.jpg?id=956) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_id=&#8221;hdr-video&#8221;][vc_column][vc_raw_html]JTNDdmlkZW8lMjBwbGF5c2lubGluZSUzRCUyMnBsYXlzaW5saW5lJTIyJTIwYXV0b3BsYXklM0QlMjJhdXRvcGxheSUyMiUyMG11dGVkJTNEJTIybXV0ZWQlMjIlMjBsb29wJTNEJTIybG9vcCUyMiUzRSUwQSUzQ3NvdXJjZSUyMHNyYyUzRCUyMmh0dHBzJTNBJTJGJTJGYmlvcHNhZmUuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIzJTJGMTAlMkZBeGxhYi1CaW9wU2FmZS1yZXZpZXctdjAxLTEubXA0JTIyJTNFJTBBJTNDJTJGdmlkZW8lM0U=[\/vc_raw_html][vc_row_inner][vc_column_inner][vc_custom_heading text=&#8221;Sicuro Facile Veloce&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css_animation=&#8221;fadeIn&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8221;intro&#8221;][vc_column][vc_row_inner el_class=&#8221;wrapper&#8221;][vc_column_inner][vc_column_text css_animation=&#8221;fadeInUp&#8221;] Formalina incapsulata nel tappo Facile da utilizzare con una semplice pressione del dito Personale non esposto [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1697126671337{margin-bottom: 5px !important;background-color: #447184 !important;}&#8221;][vc_column][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221;][vc_column_inner el_class=&#8221;box-wrap white&#8221; width=&#8221;1\/2&#8243;][vc_column_text css_animation=&#8221;fadeInUp&#8221; el_class=&#8221;box&#8221;] Risoluzione di un problema per gli&#8230; <br><br><a class=\"view-article\" href=\"https:\/\/biopsafe.com\/it\/\"><i class=\"fa fa-arrow-circle-o-right\"><\/i>L\u00e6s artikel<\/a>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-261","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/pages\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":11,"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/pages\/261\/revisions"}],"predecessor-version":[{"id":1085,"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/pages\/261\/revisions\/1085"}],"wp:attachment":[{"href":"https:\/\/biopsafe.com\/it\/wp-json\/wp\/v2\/media?parent=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}